{"id":1133,"date":"2014-01-27T06:02:06","date_gmt":"2014-01-27T11:02:06","guid":{"rendered":"https:\/\/polelineproducts.com\/?page_id=1133"},"modified":"2026-07-13T13:17:17","modified_gmt":"2026-07-13T17:17:17","slug":"protege-hauban","status":"publish","type":"page","link":"https:\/\/polelineproducts.com\/fr\/protege-hauban\/","title":{"rendered":"Protege hauban"},"content":{"rendered":"<p>Les protections ou rep\u00e8res pour haubans sont des tubes en plastique qui s&rsquo;enroulent autour des c\u00e2bles de haubanage des poteaux de services publics. Ces dispositifs simples servent \u00e0 signaler la pr\u00e9sence du c\u00e2ble afin de pr\u00e9venir les blessures. Les premi\u00e8res protections en plastique de ce type ont \u00e9t\u00e9 fabriqu\u00e9es par R&amp;M Plastic Products Ltd. ; depuis, de nombreuses am\u00e9liorations et variantes ont vu le jour. La plupart des provinces et des \u00c9tats imposent des exigences sp\u00e9cifiques concernant ces protections et, au Canada, elles doivent \u00eatre conformes aux normes de la CSA.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les protections ou rep\u00e8res pour haubans sont des tubes en plastique qui s&rsquo;enroulent autour des c\u00e2bles de haubanage des poteaux de services publics. Ces dispositifs simples servent \u00e0 signaler la pr\u00e9sence du c\u00e2ble afin de pr\u00e9venir les blessures. Les premi\u00e8res protections en plastique de ce type ont \u00e9t\u00e9 fabriqu\u00e9es par R&amp;M Plastic Products Ltd. ; [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"builder-canvas.php","meta":{"footnotes":""},"class_list":["post-1133","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/polelineproducts.com\/fr\/wp-json\/wp\/v2\/pages\/1133","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/polelineproducts.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/polelineproducts.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/polelineproducts.com\/fr\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/polelineproducts.com\/fr\/wp-json\/wp\/v2\/comments?post=1133"}],"version-history":[{"count":2,"href":"https:\/\/polelineproducts.com\/fr\/wp-json\/wp\/v2\/pages\/1133\/revisions"}],"predecessor-version":[{"id":1135,"href":"https:\/\/polelineproducts.com\/fr\/wp-json\/wp\/v2\/pages\/1133\/revisions\/1135"}],"wp:attachment":[{"href":"https:\/\/polelineproducts.com\/fr\/wp-json\/wp\/v2\/media?parent=1133"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}